{"id":1941,"date":"2019-10-23T12:35:40","date_gmt":"2019-10-23T10:35:40","guid":{"rendered":"http:\/\/blogs.hoy.es\/extremadurasecreta\/?p=1941"},"modified":"2019-11-10T12:00:58","modified_gmt":"2019-11-10T10:00:58","slug":"las-presencias-del-parador-de-merida-el-fantasma-del-nino-que-llora","status":"publish","type":"post","link":"https:\/\/blogs.hoy.es\/extremadurasecreta\/2019\/10\/23\/las-presencias-del-parador-de-merida-el-fantasma-del-nino-que-llora\/","title":{"rendered":"Las presencias del parador de M\u00e9rida: el fantasma del ni\u00f1o que llora"},"content":{"rendered":"<p><span style=\"font-size: 10pt;\">El parador de M\u00e9rida, uno de los m\u00e1s antiguos de Espa\u00f1a, es sin duda el lugar indicado para que sus paredes hayan quedado impregnadas de los \u00a0ecos del pasado.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\"><a href=\"https:\/\/blogs.hoy.es\/extremadurasecreta\/2019\/10\/15\/los-fantasmas-del-parador-de-merida-la-habitacion-encantada\/\"><strong>Ya hemos hablado en este mismo lugar de una de sus rincones m\u00e1s encantados, la habitaci\u00f3n 111<\/strong>,<\/a> que se encuentra en un pasillo estrecho y abovedado que no tiene salida.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\">Pero esta habitaci\u00f3n no es la \u00fanica que viene con inquilino invisible, y no debe ser casualidad que coincida exactamente con el pasillo que, una planta m\u00e1s arriba, tiene atemorizadas a algunas camareras de piso.<\/span><\/p>\n<div id=\"attachment_1943\" style=\"width: 1034px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-1943\" loading=\"lazy\" class=\"size-large wp-image-1943\" src=\"https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2019\/10\/12-054_edited-2-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2019\/10\/12-054_edited-2-1024x683.jpg 1024w, https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2019\/10\/12-054_edited-2-300x200.jpg 300w, https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2019\/10\/12-054_edited-2-768x512.jpg 768w, https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2019\/10\/12-054_edited-2.jpg 1728w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><p id=\"caption-attachment-1943\" class=\"wp-caption-text\"><strong><span style=\"font-size: 8pt;\">La habitaci\u00f3n 205 del parador de M\u00e9rida es una de las m\u00e1s solicitadas (Extremadura Secreta)<\/span><\/strong><\/p><\/div>\n<h3><span style=\"font-size: 12pt;\"><strong>Manolito y la habitaci\u00f3n 205<\/strong><\/span><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 10pt;\">Puri es una de ellas, y nos confesaba atemorizada que no le gusta trabajar en esas habitaciones en concreto, porque a veces las luces se apagan solas, la temperatura comienza a descender de manera brusca e incluso, en una ocasi\u00f3n, alguien o \u201calgo\u201d le abri\u00f3 el embozo de la cama que acababa de hacer en los escasos segundos en los que se volvi\u00f3 para abrir la ventana de la habitaci\u00f3n 205.<\/span><\/p>\n<div id=\"attachment_1944\" style=\"width: 1034px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-1944\" loading=\"lazy\" class=\"size-large wp-image-1944\" src=\"https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2019\/10\/20190710_012431_edited-1024x498.jpg\" alt=\"\" width=\"1024\" height=\"498\" srcset=\"https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2019\/10\/20190710_012431_edited-1024x498.jpg 1024w, https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2019\/10\/20190710_012431_edited-300x146.jpg 300w, https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2019\/10\/20190710_012431_edited-768x373.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><p id=\"caption-attachment-1944\" class=\"wp-caption-text\"><strong><span style=\"font-size: 8pt;\">La cama de la habitaci\u00f3n 205 se abri\u00f3 sola (Extremadura Secreta)<\/span><\/strong><\/p><\/div>\n<p><span style=\"font-size: 10pt;\">Las camareras de piso, para quitarse el miedo del cuerpo, le han puesto nombre al \u201cfantasma\u201d:\u00a0 Manolito. Y es que ellas est\u00e1n convencidas de que la presencia fantasmal que se encuentra por la zona de las habitaciones es la de un ni\u00f1o, quiz\u00e1s debido a estos extra\u00f1os juegos de apagar luces, deshacer camas y abrir \u00a0muebles, pero sobre todo debido a los extra\u00f1os llantos infantiles que se escuchan en ocasiones, incluso cuando no se encuentra alojado ning\u00fan ni\u00f1o en el parador.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\">Otra de las camareras de piso tambi\u00e9n escuch\u00f3 este llanto, y al buscar su origen qued\u00f3 espantada al descubrir que los gemidos infantiles proven\u00edan del interior de un armario que, como comprob\u00f3 cuando tuvo la suficiente fuerza de \u00e1nimo para abrirlo, estaba vac\u00edo.<\/span><\/p>\n<h3><\/h3>\n<h3><span style=\"font-size: 12pt;\"><strong>El ni\u00f1o que viene del fr\u00edo<\/strong><\/span><\/h3>\n<p><span style=\"font-size: 10pt;\">Pero quiz\u00e1s una de las personas que m\u00e1s de cerca han vivido estas experiencias es Helen Martin, la esposa del director del Parador, quien por motivos laborales vive con su familia en la segunda planta de este antiguo convento.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\">Vivir en un edificio tan bello y lleno de historia puede ser envidiable, pero tambi\u00e9n es cierto que a veces puede depararte sorpresas inesperadas.\u00a0 Su hijo mayor estaba convencido de que escuchaba a un ni\u00f1o en el cuarto de ba\u00f1o, y era incapaz de dormir con esa puerta abierta, mientras que su hijo peque\u00f1o no solo lo o\u00eda, sino que tambi\u00e9n ve\u00eda a ese misterios y h\u00famedo \u201cnene\u201d que lo atemorizaba con su mirada triste y sus manos fr\u00edas.<\/span><\/p>\n<div id=\"attachment_1945\" style=\"width: 1034px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-1945\" loading=\"lazy\" class=\"size-large wp-image-1945\" src=\"https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2019\/10\/IMG_1554_edited-2-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2019\/10\/IMG_1554_edited-2-1024x683.jpg 1024w, https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2019\/10\/IMG_1554_edited-2-300x200.jpg 300w, https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2019\/10\/IMG_1554_edited-2-768x512.jpg 768w, https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2019\/10\/IMG_1554_edited-2.jpg 1728w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><p id=\"caption-attachment-1945\" class=\"wp-caption-text\"><strong><span style=\"font-size: 8pt;\">Helen Martin y su familia han sido testigos de los extra\u00f1os fen\u00f3menos del parador de M\u00e9rida ( Extremadura Secreta)<\/span><\/strong><\/p><\/div>\n<p><span style=\"font-size: 10pt;\">La misma Hellen se encontr\u00f3 cara a cara con lo extra\u00f1o el d\u00eda en que oy\u00f3 a su hijo llorando en su cuarto. Alarmada, abri\u00f3 la puerta para descubrir, sorprendida, que en esa habitaci\u00f3n no hab\u00eda nadie y que su hijo se encontraba en el sal\u00f3n viendo tranquilamente la televisi\u00f3n.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\">Pero no acabaron aqu\u00ed los extra\u00f1os acontecimientos. Hace apenas unas semanas a Helen la despert\u00f3 un gran golpe. Pensando que quiz\u00e1s alguno de sus hijos se hab\u00eda levantado a beber y se hab\u00eda tropezado con un mueble, no le dio m\u00e1s importancia. Pero cuando estaba a punto de dormirse otro golpe mucho m\u00e1s fuerte volvi\u00f3 a espabilarla. Esta vez s\u00ed que se levant\u00f3, temiendo que alguien hubiese entrado en su apartamento.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\">En el pasillo, reconoci\u00f3 el origen del primer golpe que hab\u00eda escuchado:\u00a0 \u00a0unos de los antiguos puebles que utilizaba de zapatero ten\u00eda inexplicablemente las puertas abiertas de par en par. Alguien las hab\u00eda abierto con fuerza. Sigui\u00f3 avanzando por el pasillo. En la cocina encontr\u00f3 el origen del segundo golpe: alguien hab\u00eda abierto las antiguas contraventanas des de dentro y de manera violenta. Alguien, o algo, que en ese momento ella no pod\u00eda ver.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"font-size: 12pt;\"><strong>La aparici\u00f3n del ni\u00f1o fantasma<\/strong><\/span><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 10pt;\">Durante algunos a\u00f1os, aunque eran muchas las personas que hab\u00edan o\u00eddo el llanto del ni\u00f1o solo el hijo peque\u00f1o del director hab\u00eda visto al fantasma. Al menos hasta que la gobernanta del parador se lo encontr\u00f3 de cara, mir\u00e1ndola fijamente desde las puertas cerradas del comedor.<\/span><\/p>\n<div id=\"attachment_1946\" style=\"width: 1034px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-1946\" loading=\"lazy\" class=\"size-large wp-image-1946\" src=\"https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2019\/10\/12-013_edited-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2019\/10\/12-013_edited-1024x683.jpg 1024w, https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2019\/10\/12-013_edited-300x200.jpg 300w, https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2019\/10\/12-013_edited-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><p id=\"caption-attachment-1946\" class=\"wp-caption-text\"><span style=\"font-size: 8pt;\"><strong>En este lugar se apareci\u00f3 el ni\u00f1o fantasma. Al fondo, la autora entrevistando a la gobernanta desde el lugar de su visi\u00f3n. (Extremadura Secreta)<\/strong><\/span><\/p><\/div>\n<p><span style=\"font-size: 10pt;\">Ana se encontraba atareada, como siempre. Su trabajo de gobernanta la hac\u00eda recorrer el parador de punta a punta, y en ese momento llevaba entre sus brazos algunas toallas y s\u00e1banas limpias. Al ir a subir las escaleras al primer piso, observ\u00f3 con curiosidad a un extra\u00f1o ni\u00f1o \u201ccon peinado a taz\u00f3n, camisa blanca y una especie de chaleco negro\u201d que se encontraba parado y solo delante la puerta del comedor de desayunos.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\">El hecho de que esa sala estuviese cerrada a esas horas y sobre todo el aspecto de ese extra\u00f1o ni\u00f1o que la miraba en silencio la hizo desandar el camino un par de pasos para contemplarlo mejor.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\">Ana se llev\u00f3 la sorpresa de su vida al descubrir que en aquellas d\u00e9cimas de segundo que tard\u00f3 en girarse, el misterioso ni\u00f1o\u00a0 ya no la miraba desde su rinc\u00f3n. Hab\u00eda desaparecido de repente.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\">Y entonces, y solo entonces,\u00a0 supo que hab\u00eda visto al fantasma.<\/span><\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El parador de M\u00e9rida, uno de los m\u00e1s antiguos de Espa\u00f1a, es sin duda el lugar indicado para que sus paredes hayan quedado impregnadas de los \u00a0ecos del pasado. Ya hemos hablado en este mismo lugar de una de sus rincones m\u00e1s encantados, la habitaci\u00f3n 111, que se encuentra en un pasillo estrecho y abovedado [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":20,"featured_media":1947,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,12,9],"tags":[494,1430,1429,1428,1425],"_links":{"self":[{"href":"https:\/\/blogs.hoy.es\/extremadurasecreta\/wp-json\/wp\/v2\/posts\/1941"}],"collection":[{"href":"https:\/\/blogs.hoy.es\/extremadurasecreta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.hoy.es\/extremadurasecreta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.hoy.es\/extremadurasecreta\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.hoy.es\/extremadurasecreta\/wp-json\/wp\/v2\/comments?post=1941"}],"version-history":[{"count":6,"href":"https:\/\/blogs.hoy.es\/extremadurasecreta\/wp-json\/wp\/v2\/posts\/1941\/revisions"}],"predecessor-version":[{"id":1957,"href":"https:\/\/blogs.hoy.es\/extremadurasecreta\/wp-json\/wp\/v2\/posts\/1941\/revisions\/1957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.hoy.es\/extremadurasecreta\/wp-json\/wp\/v2\/media\/1947"}],"wp:attachment":[{"href":"https:\/\/blogs.hoy.es\/extremadurasecreta\/wp-json\/wp\/v2\/media?parent=1941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.hoy.es\/extremadurasecreta\/wp-json\/wp\/v2\/categories?post=1941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.hoy.es\/extremadurasecreta\/wp-json\/wp\/v2\/tags?post=1941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}