{"id":927,"date":"2014-03-24T23:37:35","date_gmt":"2014-03-24T21:37:35","guid":{"rendered":"http:\/\/blogs.hoy.es\/extremadurasecreta\/?p=927"},"modified":"2014-03-24T23:37:35","modified_gmt":"2014-03-24T21:37:35","slug":"cuando-eramos-romanos-de-cibeles-y-flagelantes","status":"publish","type":"post","link":"https:\/\/blogs.hoy.es\/extremadurasecreta\/2014\/03\/24\/cuando-eramos-romanos-de-cibeles-y-flagelantes\/","title":{"rendered":"Cuando \u00e9ramos romanos: De Cibeles y flagelantes"},"content":{"rendered":"<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<div id=\"attachment_928\" style=\"width: 227px\" class=\"wp-caption alignleft\"><a href=\"\/extremadurasecreta\/wp-content\/uploads\/sites\/16\/2014\/03\/Atis-copia.jpg\"><img aria-describedby=\"caption-attachment-928\" loading=\"lazy\" class=\"size-medium wp-image-928\" title=\"Atis copia\" src=\"\/extremadurasecreta\/wp-content\/uploads\/sites\/16\/2014\/03\/Atis-copia.jpg\" alt=\"\" width=\"217\" height=\"300\" srcset=\"https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2014\/03\/Atis-copia.jpg 2059w, https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2014\/03\/Atis-copia-218x300.jpg 218w, https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2014\/03\/Atis-copia-768x1057.jpg 768w, https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2014\/03\/Atis-copia-744x1024.jpg 744w\" sizes=\"(max-width: 217px) 100vw, 217px\" \/><\/a><p id=\"caption-attachment-928\" class=\"wp-caption-text\">Iliustraci\u00f3n: Borja Gonz\u00e1lez<\/p><\/div>\n<p style=\"text-align: justify;\">Cuando \u00e9ramos romanos, en estos d\u00edas celebr\u00e1bamos las fiestas de <strong>Cibeles<\/strong>. <a title=\"De c\u00f3mo el dios Attis se convirti\u00f3 en el compadre Manolo\" href=\"https:\/\/blogs.hoy.es\/extremadurasecreta\/2013\/03\/23\/de-como-el-dios-attis-se-convirtio-en-el-compadre-manolo\/\">El a\u00f1o pasado por estas fechas ya hablamos de <strong>Attis<\/strong> y sus<strong> falos<\/strong>,<\/a> y este a\u00f1o toca su amante, madre y compa\u00f1era, \u00a0la \u201cMagna Mater\u201d, madre de todos los dioses.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Como muchos futboleros sabr\u00e1n, Cibeles es una se\u00f1ora muy digna montada en un carro tirado por leones y con una corona \u00a0de torres almenadas que protege ciudades y naturaleza. Y algo m\u00e1s.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Su culto se extiende por Extremadura gracias a los soldados y comerciantes entre los tempraneros a\u00f1os de 108 y el 238. Tiene car\u00e1cter oracular (Como en <strong>Garlitos<\/strong>, donde se le ofrecen exvotos) y con connotaciones orgi\u00e1sticas, lo que explica su \u00e9xito en nuestra tierras, donde siempre nos ha gustado una org\u00eda y un or\u00e1culo m\u00e1s que a un tonto un l\u00e1piz. Su\u00a0 culto florece entre ciudadanos libres, aunque tambi\u00e9n se arriman a Cibeles ind\u00edgenas y esclavos.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Una de las ceremonias que le ofrec\u00edamos era la del \u201c<a title=\"Navidades paganas en Lusitania: Los misterios de Mitra y Serapis\" href=\"https:\/\/blogs.hoy.es\/extremadurasecreta\/2012\/12\/26\/navidades-paganas-en-lusitania-los-misterios-de-mitra-y-serapis\/\">taurobolium<\/a>\u201d, el sacrificio de un toro con cuya sangre nos ba\u00f1\u00e1bamos para purificarnos. Y lo hac\u00edamos a menudo en <strong>M\u00e9rida (Em\u00e9rita Augusta).<\/strong> A finales del siglo II, por ejemplo, Valeria Avita ordena hacer uno para celebrar su natalicio, y en <strong>Medellin (Metellinum)<\/strong>se sabe que tambi\u00e9n se hizo uno conmemorando la salud y el regreso a casa de alguien.<\/p>\n<div id=\"attachment_929\" style=\"width: 161px\" class=\"wp-caption alignright\"><a href=\"\/extremadurasecreta\/wp-content\/uploads\/sites\/16\/2014\/03\/dedicado-a-cibeles-por-valeria-vita-merida_edited.jpg\"><img aria-describedby=\"caption-attachment-929\" loading=\"lazy\" class=\"size-medium wp-image-929\" title=\"dedicado a cibeles por valeria vita (merida)_edited\" src=\"\/extremadurasecreta\/wp-content\/uploads\/sites\/16\/2014\/03\/dedicado-a-cibeles-por-valeria-vita-merida_edited.jpg\" alt=\"\" width=\"151\" height=\"300\" \/><\/a><p id=\"caption-attachment-929\" class=\"wp-caption-text\">Sacrificio a Cibeles (M\u00e9rida) (MNAR)<\/p><\/div>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Esta espectacular ceremonia se efectuaba ante el sacerdote correspondiente, pero tambi\u00e9n exist\u00eda un Gran Sacerdote: el archigallus, el Papa de los adoradores de Cibeles. Y este Gran Sacerdote viv\u00eda en M\u00e9rida y ten\u00eda nombre y apellidos (bien chulos, por cierto): <strong>Publicius Mysticus.<\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">La amplia difusi\u00f3n de Cibeles en nuestras tierras, como afirma el arque\u00f3logo\u00a0 se puede deber a una mezcla de razones: a la abundancia de esclavos orientales que ten\u00edamos por aqu\u00ed, al comercio de la gran Em\u00e9rita Augusta con oriente o a la asimilaci\u00f3n de Cibeles con una diosa lusitana de mucho predicamento: la diosa <strong>Ataecina<\/strong>, como afirmaba el arque\u00f3logo e historiador <strong><a title=\"La romanizaci\u00f3n, Volumen II\" href=\"http:\/\/books.google.es\/books?id=qwWmzINDuroC&#038;printsec=frontcover&#038;dq=la+romanizacion+volumen+2&#038;hl=es&#038;sa=X&#038;ei=wVkrU924JKvY0QXPhoHACg&#038;ved=0CDMQ6AEwAA#v=onepage&#038;q&#038;f=false\" rel=\"external nofollow\">Antonio Garc\u00eda Bellido<\/a><\/strong>.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Aunque otros estudiosos, como nuestro insigne <strong>Jose Maria Dominguez Moreno<\/strong>, afirma que Cibeles con quien realmente se asimila es con la ya refundida <a title=\"Nuestros dioses:  Belona la Peleona\" href=\"https:\/\/blogs.hoy.es\/extremadurasecreta\/2012\/11\/13\/nuestros-dioses-belona-la-peleona\/\">\u00a0<strong>Ma \u2013 Bellona<\/strong>, diosa guerrera<\/a> m\u00e1s dura que una rapera del Bronx, de la que ya hablamos en estas p\u00e1ginas.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Y es que al fin y al cabo, las diosas-madre suele permanecer como representaci\u00f3n de la renovaci\u00f3n eterna y se hace acompa\u00f1ar de un joven dios, hijo o esposo, representante y causante de la renovaci\u00f3n peri\u00f3dica de la Naturaleza, que mueren y resucitan, personificando de este modo la decadencia y el nacimiento de la vida, especialmente de la vida vegetal.<\/p>\n<p style=\"text-align: justify;\">\n<div id=\"attachment_930\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"\/extremadurasecreta\/wp-content\/uploads\/sites\/16\/2014\/03\/1-179_edited.jpg\"><img aria-describedby=\"caption-attachment-930\" loading=\"lazy\" class=\"size-medium wp-image-930\" title=\"1 179_edited\" src=\"\/extremadurasecreta\/wp-content\/uploads\/sites\/16\/2014\/03\/1-179_edited.jpg\" alt=\"\" width=\"300\" height=\"212\" srcset=\"https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2014\/03\/1-179_edited.jpg 1820w, https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2014\/03\/1-179_edited-300x212.jpg 300w, https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2014\/03\/1-179_edited-768x543.jpg 768w, https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2014\/03\/1-179_edited-1024x724.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-930\" class=\"wp-caption-text\">El culto a Cibeles lo extienden los soldados (A. Briz)<\/p><\/div>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Ignoramos los rituales prerromanos con los que en la Pen\u00ednsula se celebraban la muerte y la resurrecci\u00f3n del dios de la fertilidad, y tan s\u00f3lo podemos asegurar que su desarrollo coincid\u00eda con el equinocio de la primavera. Los romanos respetan unas formas de actuar que en cierto modo se parecen a las que ellos hacen en honor de las deidades encargadas del resurgir de la vida, y m\u00e1s en concreto., de la pareja <strong>Atis-Cibeles<\/strong>. Con el cristianismo sucede otro tanto. Los evangelizadores encuentran demasiados paralelismos entre los viejos mitos y la propia historia de <strong>Jes\u00fas,<\/strong> y en consecuencia los rituales antiguos pueden sostener la creencia en la muerte y en la resurrecci\u00f3n de Cristo. Atis y Jesucristo nacen de una virgen. Atis se emascula y muere junto al \u00e1rbol. Cristo se inmola en la cruz. Uno y otro resucitan para luego morir cada a\u00f1o<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Como afirma el investigador \u00a0<strong><a title=\"COFRADIAS PENITENCIALES EN EXTREMADURA\" href=\"http:\/\/www.funjdiaz.net\/folklore\/07ficha.php?id=1146\" rel=\"external nofollow\">Dom\u00ednguez Moreno<\/a><\/strong>, el dios que muere y resucita tiene su r\u00e9plica en el propio <strong>Jesucristo<\/strong> y, en consecuencia, los rituales que se hac\u00edan en honor del joven hijo o esposo de la Gran Madre, que personificaba el renacer peri\u00f3dico de la Naturaleza, se adaptan claramente al tambi\u00e9n hijo de una diosa, <strong>la Virgen Mar\u00eda,<\/strong> que fallece tr\u00e1gicamente y revive.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">As\u00ed, los disciplinantes tratan de emular a los sacerdotes de <strong>Atis<\/strong>, que anualmente se sacrificaban por estas mismas fechas. Y, efectivamente, como afirma Dom\u00ednguez, la coincidencia en el tiempo es total. Una antigua tradici\u00f3n cristiana seguida por Lactancio marca la fecha de la muerte de Cristo el 23 de marzo y la resurrecci\u00f3n el 25 del mismo mes, siendo tambi\u00e9n este \u00faltimo d\u00eda cuando se celebraba la resurrecci\u00f3n de Atis, el dios de la vegetaci\u00f3n que llevaba muerto todo el invierno. En el equinocio de primavera hac\u00edan su aparici\u00f3n los penitentes cristianos.<\/p>\n<a href=\"\/extremadurasecreta\/wp-content\/uploads\/sites\/16\/2014\/03\/altea-empalao.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-931\" title=\"altea empalao\" src=\"\/extremadurasecreta\/wp-content\/uploads\/sites\/16\/2014\/03\/altea-empalao.jpg\" alt=\"\" width=\"300\" height=\"201\" srcset=\"https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2014\/03\/altea-empalao.jpg 640w, https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/16\/2014\/03\/altea-empalao-300x202.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Y \u00a0surgen como setas por toda Extremadura las cofrad\u00edas de la Vera Cruz, tambi\u00e9n llamadas \u201cde la Sangre\u201d por razones obvias. Algunas desaparecen con el tiempo, como la de<strong> Ahigal, Oliva de M\u00e9rida, Don Alvaro, Trujillo <\/strong>o <strong>Barcarrota,<\/strong> otras reviven como la de <strong>M\u00e9rida, <\/strong>otras sobreviven, como la de <strong>Plasencia, C\u00e1ceres y Badajoz<\/strong>, y otras se convierten en parte de nuestro acervo cultura, como la de <strong>Jerez de los Caballeros <\/strong>o \u00a0<strong>Valverde de la Vera<\/strong> , donde sus disciplinantes\u00a0 \u201cempalaos\u201d recorren de noche las calles empedradas envueltos en sogas y maderos.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Cuando los disciplinantes no son \u201cempalaos\u201d tampoco el espect\u00e1culo era f\u00e1cil de ver. La procesi\u00f3n, al menos la de <strong>M\u00e9rida<\/strong>, se compon\u00eda de dos clases de hermanos: los de luz, que deb\u00edan asistir descalzos y con velas en las manos, y los flagelantes, que bajo severas penas deb\u00edan ir tapados los rostros, vestir say\u00f3n, llevar espaldas desnudas y portar unas disciplinas con las que se aplicase la voluntaria mortificaci\u00f3n, que algunas veces eran tan exageradas, seg\u00fan el <strong><a title=\"Lignum Crucis. Hermandades de Extremadura\" href=\"   http:\/\/www.lignumcrucis.es\/Hermandades\/Extremadura\/Badajoz\/Merida\/Ficha.html\">Padre Moles<\/a><\/strong>, que muchos hermanos ca\u00edan desmayados en el trayecto.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\u00bfEstamos condenados a repetir patrones a los que cambiamos el fondo pero no la forma? \u00bfServir\u00e1n realmente\u00a0 estas ceremonias anuales para preservar el orden de la naturaleza? \u00bfHasta cuando realizaremos sacrificios y derramaremos sangre para satisfacer a los dioses? Cada vez estoy m\u00e1s convencida de que nuestra evoluci\u00f3n no es m\u00e1s que un barniz que a veces se descascarilla.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Y es que, por mucho que nos empe\u00f1emos, el mismo dedo que hoy realiza fotomontajes en el\u00a0 I-Pod es el que ayer pintaba bisontes en la pared de la caverna. El mismo dedo.<\/p>\n<p style=\"text-align: justify;\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Cuando \u00e9ramos romanos, en estos d\u00edas celebr\u00e1bamos las fiestas de Cibeles. El a\u00f1o pasado por estas fechas ya hablamos de Attis y sus falos, y este a\u00f1o toca su amante, madre y compa\u00f1era, \u00a0la \u201cMagna Mater\u201d, madre de todos los dioses. Como muchos futboleros sabr\u00e1n, Cibeles es una se\u00f1ora muy digna montada en un carro [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[31,94,107,108,115,124,134,179,308,312,313,406,462,464,492,566,652,654,828,831,837,909,977,998,1162,1211,1238,1281],"_links":{"self":[{"href":"https:\/\/blogs.hoy.es\/extremadurasecreta\/wp-json\/wp\/v2\/posts\/927"}],"collection":[{"href":"https:\/\/blogs.hoy.es\/extremadurasecreta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.hoy.es\/extremadurasecreta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.hoy.es\/extremadurasecreta\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.hoy.es\/extremadurasecreta\/wp-json\/wp\/v2\/comments?post=927"}],"version-history":[{"count":0,"href":"https:\/\/blogs.hoy.es\/extremadurasecreta\/wp-json\/wp\/v2\/posts\/927\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.hoy.es\/extremadurasecreta\/wp-json\/wp\/v2\/media?parent=927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.hoy.es\/extremadurasecreta\/wp-json\/wp\/v2\/categories?post=927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.hoy.es\/extremadurasecreta\/wp-json\/wp\/v2\/tags?post=927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}