{"id":367,"date":"2013-10-26T12:20:57","date_gmt":"2013-10-26T11:20:57","guid":{"rendered":"http:\/\/blogs.hoy.es\/libreconlibros\/?p=367"},"modified":"2013-10-26T12:20:57","modified_gmt":"2013-10-26T11:20:57","slug":"mujeres-bajo-la-inquisicion","status":"publish","type":"post","link":"https:\/\/blogs.hoy.es\/libreconlibros\/2013\/10\/26\/mujeres-bajo-la-inquisicion\/","title":{"rendered":"MUJERES BAJO LA INQUISICI\u00d3N"},"content":{"rendered":"<p>Con t\u00edtulo intencionadamente provocador, Ferm\u00edn Mayor recoge en este nuevo libro un abundante conjunto de textos tomados de procesos inquistoriales contra mujeres extreme\u00f1as. Casi todos pertenecen a finales del XVIII, aunque tambi\u00e9n  los hay  de \u00e9pocas anteriores, como el muy interesante incoado a una adolescente jud\u00eda, nacida en Herrera del Duque, cuyo delito \u00fanico era intentar fortalecer en la fe mosaica a sus familiares y amigos conversos con la ilusi\u00f3n del futuro Mes\u00edas (c. 1500).<br \/>\nNi ella, ni la mayor\u00eda de las mujeres aqu\u00ed relacionadas, fueron brujas, por ambiguo que resulte este t\u00e9rmino. Bien sabido es que el temible Tribunal de la Fe espa\u00f1ol, asentado para Exremadura en Llerena, fue mucho m\u00e1s ben\u00e9volo  con aquellas que otras instancias jur\u00eddicas europeas. El autor reconoce que, a lo largo de m\u00e1s de tres siglos, no pronunci\u00f3 sentencia de muerte contra ninguna de las mismas, si bien no pocas sufrir\u00edan penas como embargo de bienes, azotes o destierro de sus localidades. Recordemos la &#8220;doctrina&#8221; asentada por Pedro de Valencia en su c\u00e9lebre Discurso de Pedro de Valencia acerca de los cuentos de las brujas y cosas tocantes a magia, dirigido al Ilmo. Sr. D. Bernardo de Sandoval y Rojas, donde se reduce el mundo brujeril a conductas f\u00e1cilmente explicables por factores naturales. Otra cosa es que la fantas\u00eda, el miedo, el inter\u00e9s, la imaginaci\u00f3n, las p\u00f3cimas dopantes, la enfermedad mental, la tortura misma  u otros elementos plagasen los relatos. Caro Baroja  ya lo explic\u00f3 definitivamente.<br \/>\nLos textos de las actas aqu\u00ed reproducidos en cursiva  (los comentarios del autor, superfluamente reiterativos, est\u00e1n en caja baja)  aluden a mujeres de bien distinta clase y condici\u00f3n: curanderas, comadres, saludadoras, alcahuetas, adivinas, rezadoras, hechiceras, monjas ilusas o solicitadas, beatas p\u00edcaras, veoras, etc., de las que no faltar\u00edan pr\u00e1cticamente en ninguna localidad, ser\u00e1n procesadas, casi siempre por delaci\u00f3n de familiares o vecinos.  Advirtamos lo que Norma Bl\u00e1zquez, profesora de la UNAMN, explica en El retorno de las brujas y que, no es solamente v\u00e1lido para la \u00e9poca medieval, pues los arquetipos culturales peviven durante siglos: Fueron mujeres con conocimientos espec\u00edficos en alquimia, con los que elaboraban recetas de perfumer\u00eda y cosm\u00e9tica. Desarrollaron t\u00e9cnicas de destilaci\u00f3n, extracci\u00f3n y sublimaci\u00f3n. Eran parteras, alquimistas, perfumistas, nodrizas o cocineras que ten\u00edan conocimiento en campos como la anatom\u00eda, la bot\u00e1nica, la sexualidad, el amor o la reproducci\u00f3n, y que prestaban un importante servicio a la comunidad. Conoc\u00edan mucho de plantas, animales y minerales, y creaban recetas para curar, lo cual fue interpretado por los grupos dominantes del medievo como un poder del Diablo. Fueron perseguidasporque las elites eclesi\u00e1sticas, pol\u00edticas y econ\u00f3micas, que se consolidaban en aquellos tiempos, comenzaron a desarrollar un modelo social muy masculino y consideraban que el saber que las mujeres ten\u00edan, especialmente en sexualidad y reproducci\u00f3n, representaba una amenaza.<br \/>\nLa cuesti\u00f3n pod\u00eda complic\u00e1rselas si, seg\u00fan ocurre a veces, se provocan sospechas de herej\u00eda luterana, complicidad con judeoconversos o moriscos rebeldes, sacrilegios, abusos en los sacramentos de la confesi\u00f3n o eucarist\u00eda, etc.<br \/>\nLos lugares con mayor n\u00famero de mujeres encausadas ser\u00edan Plasencia, Zafra y , sobre todo, Jerez de los Caballeros, al que el autor llama enf\u00e1ticamene &#8220;el Pueblo de las Brujas&#8221;, seg\u00fan se deduce del &#8220;autillo&#8221; celebrado en la Inquisici\u00f3n de Llerena el a\u00f1o 1637 contra 22 mujeres jerezanas y un hombre (ver pp.153-160). Es muy curioso que el ensalmo propuesto por una de ellas para atraer a los varones  incluya &#8220;la oraci\u00f3n de San Erasmo&#8221;, cuyo texto se reproduce.<\/p>\n<p>Ferm\u00edn Mayorga, Extremadura: Tierra de Brujas. Don Benito, Grupo de Estudios de las Vegas Altas, 2013.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con t\u00edtulo intencionadamente provocador, Ferm\u00edn Mayor recoge en este nuevo libro un abundante conjunto de textos tomados de procesos inquistoriales contra mujeres extreme\u00f1as. Casi todos pertenecen a finales del XVIII, aunque tambi\u00e9n los hay de \u00e9pocas anteriores, como el muy interesante incoado a una adolescente jud\u00eda, nacida en Herrera del Duque, cuyo delito \u00fanico era [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/posts\/367"}],"collection":[{"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/comments?post=367"}],"version-history":[{"count":0,"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/posts\/367\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/media?parent=367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/categories?post=367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/tags?post=367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}