{"id":368,"date":"2013-11-02T11:33:29","date_gmt":"2013-11-02T10:33:29","guid":{"rendered":"http:\/\/blogs.hoy.es\/libreconlibros\/?p=368"},"modified":"2013-11-02T11:33:29","modified_gmt":"2013-11-02T10:33:29","slug":"personajes-extremenos-2","status":"publish","type":"post","link":"https:\/\/blogs.hoy.es\/libreconlibros\/2013\/11\/02\/personajes-extremenos-2\/","title":{"rendered":"PERSONAJES  EXTREME\u00d1OS"},"content":{"rendered":"<p>Fue en una edici\u00f3n de amigos (2001),  con muy corta tirada (300 ejemplares), la vez primera que vio luz esta obra, escrita quiz\u00e1s un lustro antes, lo que acaso provoca la confusi\u00f3n de fechas en las palabras preliminares que el autor pone a este segunda. Se trata de la biograf\u00eda novelesca de un personaje imaginario, realmente atractivo, aunque de dudosa verosimilitud. Enrique S\u00e1nchez de Le\u00f3n (Badajoz, 1934) lo hace el protagonista en este relato complejo, que tiene m\u00e1s de estudio hist\u00f3rico, ensayo sociopol\u00edtico e incluso antropolog\u00eda, que de literatura.<\/p>\n<p>Trasunto en buen grado del propio autor, Quico Cort\u00e9s, regionalista confeso, curtido y amable, un punto ut\u00f3pico, decide convocar en M\u00e9rida una jornada de reflexi\u00f3n, forzosamente clandestina, a los m\u00e1s conspicuos paisanos de su \u00e9poca con el fin de establecer entre todos el programa de acci\u00f3n que saque a Extremadura de sus seculares carencias. Tampoco el pa\u00eds pasaba entonces por los mejores momentos. El escritor nos retrotrae a 1829, cuando Espa\u00f1a contin\u00faa bajo la f\u00e9rula absolutista de Fernando  VII, contumaz en perseguir a los defensores de la \u201cPepa\u201d, la constituci\u00f3n liberal de 1812 para cuyo \u00e9xito fue clave el papel de los diputados extreme\u00f1os.<\/p>\n<p>Generoso y pac\u00edfico anfitri\u00f3n, Cort\u00e9s consigue reunir a representantes de todo el arco parlamentario. Otra cosa es lograr que, como hijos de una tierra extremada, respeten turnos de intervenciones, escuchen y dialoguen civilizadamente, razonen en vez de agredir y est\u00e9n m\u00e1s proclives al bien com\u00fan que al particular.<\/p>\n<p>Desde luego, ni el moderador m\u00e1s templado habr\u00eda tenido f\u00e1cil conducir una mesa donde se sentasen  el general\u00edsimo Manuel Godoy, el bibli\u00f3grafo y polemista Bartolom\u00e9 J. Gallardo, el cura  progresista Mu\u00f1oz Torrero, el tecn\u00f3crata Bravo Murillo, el militroncho liberal (sic) Fern\u00e1ndez Golf\u00edn, el poeta rom\u00e1ntico Espronceda, el reformista Jos\u00e9 Mar\u00eda Calatrava, el obispo ambiguo e inquisidor Casquete de Prado y el ultraconservador Donoso Cort\u00e9s. M\u00e1s complicado ser\u00e1 a\u00fan el encuentro si, seg\u00fan ocurre en la segunda jornada, se suman otros personajes muy secundarios, que S\u00e1nchez de Le\u00f3n concita de entre sus propios coet\u00e1neos. No s\u00f3lo no lograr\u00e1n establecer un programa de m\u00ednimos, sino ni siquiera ponerse de acuerdo sobre los rasgos o caracteres (geogr\u00e1ficos, hist\u00f3ricos, etnogr\u00e1ficos, pol\u00edticos\u2026 o de cualquier orden) aptos para identificar a Extremadura como regi\u00f3n, definir su personalidad, rastre\u00e1ndolos desde la Lusitania hasta hoy. Romanizaci\u00f3n,  Islam Reconquista y \u00d3rdenes Militares, Guadalupe, Conquista y colonizaci\u00f3n americanas, Guerras contra Portugal, Guerra de la Independencia, liberalismo constitucional&#8230; ser\u00e1n fen\u00f3menos analizados desde diferentes posiciones.<\/p>\n<p>En verdad, el aut\u00e9ntico protagonista de la obra es ese narrador omnisciente, que apenas permite respiro a los dem\u00e1s. Abruma al lector con datos, nombres, fechas y consideraciones personales, casi todas nimbadas de un hondo pesimismo sobre el car\u00e1cter de los extreme\u00f1os y, en consecuencia, su futuro.<\/p>\n<p>Abre el libro una larga  e iluminadora entrevista-pr\u00f3logo (pp. 9-20) que Jos\u00e9 Juli\u00e1n Barriga Bravo mantiene con el escritor. \u00c9ste ha tenido el acierto de sustituir el \u201ccast\u00fao\u201d de la primera edici\u00f3n por el castellano, si bien ha querido mantener el habla dialectal en la dedicatoria, que comienza as\u00ed: \u201cA todos los ringaoh, loh marru\u00f1oh, lo\u00b4hagachaoh, lo\u00b4jaroneh, lo\u00b4hapergollaoh, loh cagarracheh, loh concalecioh, lo. Handarrioh, loh carajamandogah, loh somioh\u201d, etc. Sin duda, mejor dejarlo.<\/p>\n<p>Enrique S\u00e1nchez de L\u00e9on, \u2026Pero no se dobla (o la biograf\u00eda de Quico Cort\u00e9s). Madrid, Beturia, 2013.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fue en una edici\u00f3n de amigos (2001), con muy corta tirada (300 ejemplares), la vez primera que vio luz esta obra, escrita quiz\u00e1s un lustro antes, lo que acaso provoca la confusi\u00f3n de fechas en las palabras preliminares que el autor pone a este segunda. Se trata de la biograf\u00eda novelesca de un personaje imaginario, [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/posts\/368"}],"collection":[{"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/comments?post=368"}],"version-history":[{"count":0,"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/posts\/368\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/media?parent=368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/categories?post=368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/tags?post=368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}