{"id":374,"date":"2013-11-24T10:56:44","date_gmt":"2013-11-24T09:56:44","guid":{"rendered":"http:\/\/blogs.hoy.es\/libreconlibros\/?p=374"},"modified":"2013-11-24T10:56:44","modified_gmt":"2013-11-24T09:56:44","slug":"alla-en-los-balkanes","status":"publish","type":"post","link":"https:\/\/blogs.hoy.es\/libreconlibros\/2013\/11\/24\/alla-en-los-balkanes\/","title":{"rendered":"ALL\u00c1, EN LOS BALKANES"},"content":{"rendered":"<p>&#8220;En la \u00e9poca en que comienza esta historia quedaban todav\u00eda gentes de otro tiempo que eran partidarios de la idea, y de la quimera, de que en los Balkanes hab\u00eda un gran pa\u00eds, un pa\u00eds unido y cohesionado, en otra Europa&#8221;. As\u00ed lo proclama el autor de esta compleja narraci\u00f3n casi al final de la misma (p\u00e1g. 427), no sin advertir que tras lo sucedido a\u00f1os antes, ya no era posible recomponer aquella valiosa amalgama de culturas. Acaso, reformar algunas peque\u00f1as cosas en l\u00ednea con su tesis: la antigua cohesi\u00f3n no era fruto de m\u00e9todos coercitivos, sino de una competencia constituida a lo largo de muchas generaciones. Eso se llama fe en un pueblo, la misma que mantiene, pese a todo, el grupo de personas atra\u00eddas a \u201cLa noche del Morava\u201d \u2013 nombre de una embarcaci\u00f3n anclada en las orillas del viejo r\u00edo balk\u00e1nico \u2013 por el due\u00f1o de la nao. Se trata de un experto autor, ya  cansado de escribir. Durante la velada nocturna que durar\u00e1 el relato, quiere referirle a sus amigos y una enigm\u00e1tica mujer las peripecias por \u00e9l vividas en un viaje circular, odisea de car\u00e1cter inici\u00e1tico, con principio y fin en Porodin (ya en caracteres latinos, no cir\u00edilos, irritantes para otros) a orillas del afluente del Danubio, tal vez Kosovo, encarnaci\u00f3n de la estragada Serbia. Otros lugares simb\u00f3licos, como la Numancia espa\u00f1ola destruida por los romanos tras heroica resistencia, o una Samarcanda on\u00edrica, aparecer\u00e1n en este alucinador periplo, que transcurre por los Balkanes, la Pen\u00ednsula ib\u00e9rica, Austria y Alemania, hasta regresar a los or\u00edgenes.<br \/>\nEl narrador es un \u00e1lter ego del propio Peter Handke quien, seg\u00fan su costumbre,  y ayud\u00e1ndose de otro relator intermedio, ir\u00e1 combinando en el texto reflexiones metaliterarias, descripciones paisaj\u00edsticas y apuntes filos\u00f3ficos sobre soledad el sentido de la historia y de la muerte; las relaciones hombre-mujer, especialmente problem\u00e1ticas trat\u00e1ndose de un escritor; la psicolog\u00eda de las poblaciones; los recuerdos infantiles; los nacionalismos exacerbados; el ruido y sus v\u00edctimas; la crueldad est\u00fapida (peor  la infantil) o  las  paradojas de la pol\u00edtica europea. Todo ello sin ocultar sus propias dudas, sue\u00f1os y frustraciones, dej\u00e1ndose atraer en numerosas ocasiones , seguramente las m\u00e1s brillantes, por esa pulsi\u00f3n ling\u00fc\u00edstica que remite a las ra\u00edces del surrealismo.<br \/>\nNatural (n. 1942) de Griffen, en la regi\u00f3n fronteriza de Carintia, con hondas ra\u00edces familiares eslovenas, Handke reside en Francia y tiene una obra tan plural (novela, teatro, poes\u00eda, ensayo, periodismo, guiones de cine, traducci\u00f3n) como reconocida. No obstante, a este austr\u00edaco rebelde, iconoclasta e inc\u00f3modo, muchos no le perdonan (v.c., las editoriales brit\u00e1nicas reh\u00fasan publicarle) la obstinada defensa de la antigua Yugoslavia o sus pol\u00e9micas declaraciones sobre dirigentes como Milosevi\u0107.<br \/>\nAutor de otros libros que conviene recordar ahora : Un viaje de invierno a los r\u00edos Danubio, Save, Morava y Drina, o justicia para Serbia (1996) Die Kuckucke von Velika Hoca ( 2009), o Immer noch Stur (drama sobre la lucha de los partisanos eslovenos contra Hitler y sus c\u00f3mplices croatas), Handke ha vuelto a escribir una magn\u00edfica novela, en la que no oculta sus opciones vitales, si bien atemperadas por la sabidur\u00eda y la piedad hacia los hombres  allegadas con el transcurso de los a\u00f1os. La noche del Morava (Die morawische Nacht, 2008), excelentemente traducida por Eustaquio Barjau, es un texto personal\u00edsimo, no s\u00e9 si con excesivas digresiones, cargado de  sutiles sugerencias y multitud de juegos de lenguaje, escrito con una singular t\u00e9cnica de alejamiento, que nunca distancia al lector, por alguien que gusta parafrasear el adagio cl\u00e1sico y defender \u201cut poesis, prosa\u201d. Constituye ante todo un  emotivo canto a los Balkanes (palabra maldita para muchos) cuyo futuro podr\u00eda no ser tan triste como algunos presagiaron.<\/p>\n<p>Peter Handke, La noche del Morava. Madrid, Alianza, 2013.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;En la \u00e9poca en que comienza esta historia quedaban todav\u00eda gentes de otro tiempo que eran partidarios de la idea, y de la quimera, de que en los Balkanes hab\u00eda un gran pa\u00eds, un pa\u00eds unido y cohesionado, en otra Europa&#8221;. As\u00ed lo proclama el autor de esta compleja narraci\u00f3n casi al final de la [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/posts\/374"}],"collection":[{"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/comments?post=374"}],"version-history":[{"count":0,"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/posts\/374\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/media?parent=374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/categories?post=374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.hoy.es\/libreconlibros\/wp-json\/wp\/v2\/tags?post=374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}