{"id":692,"date":"2014-11-26T10:59:55","date_gmt":"2014-11-26T08:59:55","guid":{"rendered":"http:\/\/blogs.hoy.es\/meteobadajoz\/?p=692"},"modified":"2014-11-26T10:59:55","modified_gmt":"2014-11-26T08:59:55","slug":"llega-la-primera-gran-borrasca-de-la-temporada","status":"publish","type":"post","link":"https:\/\/blogs.hoy.es\/meteobadajoz\/2014\/11\/26\/llega-la-primera-gran-borrasca-de-la-temporada\/","title":{"rendered":"Llega a Espa\u00f1a la primera gran borrasca de la temporada"},"content":{"rendered":"<p align=\"LEFT\"><strong><span style=\"color: #000000;\"><span style=\"font-size: 14px;\"><span style=\"font-family: 'Segoe UI';\">\u00bb<\/span><\/span><span style=\"color: #000000;\"><span style=\"font-size: 14px;\"><span style=\"font-family: 'Segoe UI', sans-serif;\">\u00a0Este jueves-viernes tendremos un breve temporal en la pen\u00ednsula debido a la llegada de una profunda borrasca, que dejar\u00e1 lluvias muy abundantes en todo el oeste y sur peninsular, acompa\u00f1ado de fuertes rachas de viento.<\/span><\/span><\/span><\/span><\/strong><\/p>\n<p style=\"text-align: center;\" align=\"CENTER\"><strong><\/strong><strong><span style=\"color: #000000;\"><span style=\"font-size: 12px;\"><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span><img loading=\"lazy\" class=\"aligncenter\" src=\"\/\/nsae02.casimages.net\/img\/2014\/11\/26\/141126125840361879.png\" alt=\"\" width=\"592\" height=\"305\" \/>Evoluci\u00f3n prevista de la borrasca, a fecha del lunes 24\/11\/2014 &#8211; \u00a9 MeteoBadajoz<\/span><\/span><\/span><\/span><\/strong><\/p>\n<p align=\"LEFT\"><span style=\"color: #000000;\"><span style=\"font-size: 12px;\"><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span><strong>Mi\u00e9rcoles 26 de Noviembre 2014.<\/strong><\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-size: 12px;\"><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span> Se confirmaban poco a poco los cambios que ven\u00edamos siguiendo en los \u00faltimos d\u00edas ante, lo que podr\u00eda ser, <strong>la llegada de una profunda borrasca<\/strong> al oeste peninsular, cuyas consecuencias quedar\u00edan reflejadas en forma de lluvias bastante abundantes y fuertes rachas de viento (70-90 km\/h) en el suroeste peninsular.<\/span><\/span><\/span><\/span><\/span><\/p>\n<p align=\"LEFT\"><span style=\"color: #000000;\"><span style=\"font-size: 12px;\"><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span>Pues bien, parece que finalmente se confirman esos pron\u00f3sticos, y parece claro que este jueves-viernes una profunda borrasca acabar\u00e1 al oeste peninsular, dej\u00e1ndonos la entrada de <strong>un frente fr\u00edo muy activo<\/strong>, con precipitaciones generosas, abundantes y localmente intensas.<!--more--><\/span><\/span><\/span><\/span><\/p>\n<p align=\"LEFT\"><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span style=\"font-size: 12px;\">En la ilustraci\u00f3n superior pod\u00e9is ver de d\u00f3nde nos llega esta nueva borrasca; nada m\u00e1s y nada menos que desde el interior de Norteam\u00e9rica, donde la semana pasada se formaba por la existencia de un nuevo desalojo \u00e1rtico sobre EE.UU. y Canad\u00e1 (menos intenso que el de d\u00edas atr\u00e1s), que al interaccionar con el aire c\u00e1lido y h\u00famedo que sube desde el Golfo de M\u00e9xico,\u00a0dio\u00a0lugar a su formaci\u00f3n y posterior\u00a0profundizaci\u00f3n. Hoy la tenemos reci\u00e9n salida\u00a0de\u00a0Canad\u00e1, y de hecho\u00a0<strong>est\u00e1 ya camino de la pen\u00ednsula<\/strong>!<\/span><\/span><\/p>\n<p align=\"LEFT\"><span style=\"color: #000000;\"><span style=\"font-size: 12px;\"><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span>Pero mientras llega, ya este mi\u00e9rcoles por la tarde-noche tendremos la entrada de <strong>un primer frente<\/strong> desde el oeste, por el acercamiento de una peque\u00f1a borrasca que precede a la \u201c<em>borrasca madre<\/em>\u201d que viene detr\u00e1s (la del jueves-viernes). De momento las lluvias de este mi\u00e9rcoles-jueves no ser\u00e1n demasiado importantes, o al menos no tendr\u00e1n nada que ver con las que se esperan para el jueves-viernes, <strong>que s\u00ed ser\u00edan de importancia<\/strong>.<\/span><\/span><\/span><\/span><\/p>\n<p style=\"text-align: center;\" align=\"CENTER\"><span style=\"color: #000000;\"><span style=\"font-size: 12px;\"><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span><strong><img loading=\"lazy\" class=\"aligncenter\" src=\"\/\/nsae02.casimages.net\/img\/2014\/11\/26\/141126125729249859.png\" alt=\"\" width=\"547\" height=\"298\" \/>Lluvias muy abundantes y localmente intensas en todo el oeste y sur peninsular este jueves-viernes (27 y 28 de Nov. 2014) \u2013 Modelo IFS\/ECMWF<\/strong><\/span><\/span><\/span><\/span><\/p>\n<p align=\"LEFT\"><span style=\"color: #000000;\"><span style=\"font-size: 12px;\"><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span>Como pod\u00e9is ver en el mapa superior, el <strong>gran impacto<\/strong> del frente en la pen\u00ednsula<strong> promete dejar importantes acumulaciones de lluvia<\/strong>\u00a0(y eso s\u00f3lo durante el paso del frente), siendo m\u00e1s cuantiosas sobre todo en aquellas zonas que est\u00e9n m\u00e1s expuestas (Portugal, Extremadura y el oeste e interior de Andaluc\u00eda, principalmente).<\/span><\/span><\/span><\/span><\/p>\n<p align=\"LEFT\"><span style=\"color: #000000;\"><span style=\"font-size: 12px;\"><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span>Atenci\u00f3n a <strong>posibles inundaciones ante excesos de precipitaci\u00f3n<\/strong> en amplias zonas del oeste y suroeste peninsular, ya que tanta lluvia en tantas zonas podr\u00eda acabar dejando algunos problemas, a<\/span><\/span><\/span><\/span><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: 12px;\">unque la buena noticia es que la parte m\u00e1s importante del temporal <strong>pasar\u00eda a lo largo de la madrugada<\/strong>, as\u00ed que a muchos nos coger\u00e1 en casa.<\/span><\/p>\n<p style=\"text-align: center;\" align=\"CENTER\"><span style=\"color: #000000;\"><span style=\"font-size: 12px;\"><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span><strong><img loading=\"lazy\" class=\"aligncenter\" src=\"\/\/nsae02.casimages.net\/img\/2014\/11\/26\/14112612581259949.png\" alt=\"\" width=\"547\" height=\"307\" \/>Lluvias abundantes y localmente intensas en el este y noreste peninsular el s\u00e1bado-domingo (29 y 30 de Nov. 2014) \u2013 Modelo IFS\/ECMWF<\/strong><\/span><\/span><\/span><\/span><\/p>\n<p align=\"LEFT\"><span><span><span><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span style=\"font-size: 12px;\">Entre el viernes y el s\u00e1bado, la borrasca y su frente fr\u00edo asociado acabar\u00edan llegando al Mediterr\u00e1neo, y ojo porque por all\u00ed tambi\u00e9n tendr\u00e1n una situaci\u00f3n de <\/span><\/span><strong style=\"color: #000000; font-family: Arial, Helvetica, sans-serif; font-size: 12px;\">lluvias bastante importantes<\/strong><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span style=\"font-size: 12px;\"> a lo largo del fin de semana.\u00a0<\/span><\/span><\/span><\/span><\/span><span style=\"font-size: 12px; font-family: Arial, Helvetica, sans-serif;\">La borrasca centrada al sureste peninsular, genera un flujo de vientos del este y sureste de bastante recorrido mar\u00edtimo sobre el Mediterr\u00e1neo, y las\u00a0consecuentes\u00a0lluvias en todo el levante peninsular, y\u00a0especialmente\u00a0hacia el noreste<\/span><\/p>\n<p align=\"CENTER\"><span style=\"color: #000000;\"><span style=\"font-size: 12px;\"><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span><strong><img loading=\"lazy\" class=\"aligncenter\" src=\"\/\/nsae02.casimages.net\/img\/2014\/11\/26\/141126125950297048.gif\" alt=\"\" width=\"586\" height=\"480\" \/>Rachas m\u00e1ximas de viento en superficie fuertes o muy fuertes entre el jueves 27 (22:00h) y el viernes 28 (11:00h) \u2013 Modelo\u00a0WRF-NMM 5km<\/strong><\/span><\/span><\/span><\/span><\/p>\n<p align=\"LEFT\"><span><span><span><span><span><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span style=\"font-size: 12px;\">A fecha de hoy, los modelos a\u00fan no tienen claro d\u00f3nde se ubicar\u00e1 exactamente la borrasca del jueves-viernes, aunque la\u00a0mayor\u00eda\u00a0de ellos parecen estar de\u00a0acuerdo en que ser\u00e1 muy profunda. Se manejan cifras de entre <\/span><\/span><\/span><\/span><strong style=\"color: #000000; font-family: Arial, Helvetica, sans-serif; font-size: 12px;\">980 hPa y hasta 970 hPa<\/strong><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span style=\"font-size: 12px;\"> de presi\u00f3n en su centro, lo cual la convierte en <\/span><\/span><strong style=\"color: #000000; font-family: Arial, Helvetica, sans-serif; font-size: 12px;\">una borrasca bastante profunda<\/strong><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span style=\"font-size: 12px;\">, que s\u00f3lo en contadas ocasiones tenemos en nuestra zona; aunque tampoco es nada raro, y menos en oto\u00f1o, que siempre nos deja la llegada de borrascas muy\u00a0profundas\u00a0y activas desde el Atl\u00e1ntico.<\/span><\/span><\/span><\/span><\/span><\/p>\n<p align=\"LEFT\"><span><span><span><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span style=\"font-size: 12px;\">De cualquier manera, esta profunda borrasca ser\u00e1 capaz de desarrollar<\/span><\/span><strong style=\"color: #000000; font-family: Arial, Helvetica, sans-serif; font-size: 12px;\"> vientos m\u00e1ximos de 70-90 km\/h<\/strong><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span style=\"font-size: 12px;\"> justo por delante del frente, en una zona donde el viento se acelera y las rachas pueden llegar a ser bastante fuertes. <\/span><\/span><span style=\"color: #000000; font-family: Arial, Helvetica, sans-serif; font-size: 12px; text-decoration: underline;\"><strong>Recomendable<\/strong><\/span><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span style=\"font-size: 12px;\"> dejar terrazas, azoteas y balcones limpios de objetos que puedan ser lanzados por el viento, y as\u00ed <strong>reducimos riesgos en ciudad ante situaciones adversas<\/strong> como la que se nos presenta en los pr\u00f3ximos d\u00edas.<\/span><\/span><\/span><\/span><\/span><\/p>\n<p align=\"LEFT\"><span style=\"color: #000000;\"><span style=\"font-size: 12px;\"><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span>-En definitiva: llega un nuevo temporal de lluvia y viento a la pen\u00ednsula, y aunque parece que s\u00f3lo durar\u00e1 una cuantas horas, puntualmente en la madrugada del jueves al viernes nos puede dejar <strong>registros importantes de lluvia y viento<\/strong> durante el paso del frente.<\/span><\/span><\/span><\/span><\/p>\n<p align=\"LEFT\"><span style=\"color: #000000;\"><span style=\"font-size: 12px;\"><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span>Por otro lado, adem\u00e1s de este tiempo inestable,\u00a0<\/span><\/span><\/span><\/span><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span style=\"font-size: 12px;\">las temperaturas no parece que vayan a\u00a0sufrir\u00a0demasiados cambios en los pr\u00f3ximos d\u00edas: tras un inicio de semana c\u00e1lido con temperaturas rondando los 20-22\u00baC, lo que cabe esperar es que <strong>las temperaturas se\u00a0normalicen<\/strong>, con valores de 14-15\u00baC de m\u00e1xima, y m\u00ednimas\u00a0alrededor de los 8-10\u00baC.<\/span><\/span><\/p>\n<p align=\"LEFT\"><span><span><span><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span style=\"font-size: 12px;\">De cara al fin de semana parece que volver\u00edan a subir hasta los 18-19\u00baC, aunque a medio-largo plazo (la pr\u00f3xima semana) parece que volver\u00edan a bajar, y quiz\u00e1s bastante, por la llegada de aire fr\u00edo desde el\u00a0interior\u00a0de Europa&#8230; ya veremos, de momento lo que debemos tener es\u00a0<strong>PRECAUCI\u00d3N este jueves-viernes<\/strong>!<\/span><\/span><\/span><\/span><\/span><\/p>\n<p align=\"LEFT\"><span style=\"color: #ffffff;\"><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span>.<\/span><\/span><\/span><\/p>\n<p align=\"CENTER\"><span style=\"color: #808080;\"><span style=\"font-size: 12px;\"><span style=\"font-family: Arial, Helvetica, sans-serif;\">Por Javier Pi\u00f1ero Fuentes &#8211; \u00a9 MeteoBadajoz 2014<\/span><\/span><\/span><\/p>\n<p align=\"CENTER\"><span style=\"color: #808080;\"><span style=\"font-size: 12px;\"><span style=\"font-family: arial, sans-serif;\">meteobadajoz@gmail.com<\/span><\/span><\/span><\/p>\n<p align=\"CENTER\"><strong><span style=\"color: #000000;\"><span style=\"font-size: 12px;\"><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span>Puedes seguir cada situaci\u00f3n a trav\u00e9s de la cuenta de Twitter <\/span><\/span><\/span><\/span><\/strong><strong><a href=\"https:\/\/twitter.com\/MeteoBadajoz\" target=\"_blank\" rel=\"external nofollow\"><span style=\"color: #ff0000;\"><span style=\"font-size: 12px;\"><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span>@MeteoBadajoz<\/span><\/span><\/span><\/span><\/a><\/strong><strong><span style=\"color: #000000;\"><span style=\"font-size: 12px;\"><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span>, o Facebook <\/span><\/span><\/span><\/span><\/strong><strong><a href=\"https:\/\/www.facebook.com\/pages\/MeteoBadajoz\/236436716399890\" target=\"_blank\" rel=\"external nofollow\"><span style=\"color: #ff0000;\"><span style=\"font-size: 12px;\"><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span>MeteoBadajoz<\/span><\/span><\/span><\/span><\/a><\/strong><strong><span style=\"color: #000000;\"><span style=\"font-size: 12px;\"><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span>, donde estar\u00e1s informado en todo momento de c\u00f3mo evolucionan los d\u00edas, as\u00ed como de noticias de inter\u00e9s meteorol\u00f3gico.<\/span><\/span><\/span><\/span><\/strong><\/p>\n<p align=\"CENTER\"><strong><span style=\"color: #000000;\"><span style=\"font-size: 12px;\"><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span><span style=\"text-decoration: underline;\"><strong>Si el art\u00edculo te ha parecido interesante, puedes ayudar a divulgarlo a trav\u00e9s de las redes sociales, con ayuda de los botones para compartir.<\/strong><\/span><\/span><\/span><\/span><\/span><\/strong><\/p>\n<p align=\"CENTER\"><strong><span style=\"color: #000000;\"><span style=\"font-size: 12px;\"><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span>\u00a1\u00a1Gracias y un saludo a los lectores del blog!!<\/span><\/span><\/span><\/span><\/strong><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>\u00bb\u00a0Este jueves-viernes tendremos un breve temporal en la pen\u00ednsula debido a la llegada de una profunda borrasca, que dejar\u00e1 lluvias muy abundantes en todo el oeste y sur peninsular, acompa\u00f1ado de fuertes rachas de viento. Evoluci\u00f3n prevista de la borrasca, a fecha del lunes 24\/11\/2014 &#8211; \u00a9 MeteoBadajoz Mi\u00e9rcoles 26 de Noviembre 2014. Se confirmaban [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":75,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,5],"tags":[7,12,33,83,110,117,122,143],"_links":{"self":[{"href":"https:\/\/blogs.hoy.es\/meteobadajoz\/wp-json\/wp\/v2\/posts\/692"}],"collection":[{"href":"https:\/\/blogs.hoy.es\/meteobadajoz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.hoy.es\/meteobadajoz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.hoy.es\/meteobadajoz\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.hoy.es\/meteobadajoz\/wp-json\/wp\/v2\/comments?post=692"}],"version-history":[{"count":0,"href":"https:\/\/blogs.hoy.es\/meteobadajoz\/wp-json\/wp\/v2\/posts\/692\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.hoy.es\/meteobadajoz\/wp-json\/wp\/v2\/media?parent=692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.hoy.es\/meteobadajoz\/wp-json\/wp\/v2\/categories?post=692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.hoy.es\/meteobadajoz\/wp-json\/wp\/v2\/tags?post=692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}