{"id":196,"date":"2017-05-15T20:25:28","date_gmt":"2017-05-15T18:25:28","guid":{"rendered":"http:\/\/blogs.hoy.es\/musica-en-el-tiempo\/?p=196"},"modified":"2017-05-21T18:41:26","modified_gmt":"2017-05-21T16:41:26","slug":"siempre-te-voy-a-esperar","status":"publish","type":"post","link":"https:\/\/blogs.hoy.es\/musica-en-el-tiempo\/2017\/05\/15\/siempre-te-voy-a-esperar\/","title":{"rendered":"Siempre te voy a esperar"},"content":{"rendered":"<p><a href=\"https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/114\/2017\/05\/IMG-20170517-WA0000.jpg\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-199\" src=\"https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/114\/2017\/05\/IMG-20170517-WA0000.jpg\" alt=\"\" width=\"720\" height=\"381\" srcset=\"https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/114\/2017\/05\/IMG-20170517-WA0000.jpg 720w, https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/114\/2017\/05\/IMG-20170517-WA0000-300x159.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p>El pueblo de Hornachos aguanta la respiraci\u00f3n desde que el pasado 9 de Mayo nuestra vecina Francisca Cadenas desapareciera de forma inexplicable, dejando a su familia y a todos los que la conoc\u00edamos sin saber qu\u00e9 hacer, m\u00e1s all\u00e1 de seguir busc\u00e1ndola por las cercan\u00edas, compartir su imagen en los medios de comunicaci\u00f3n, enviar carteles e intentar implicar en su b\u00fasqueda a todos aquellos que puedan dar alguna pista sobre su paradero.<\/p>\n<p>Hoy nuestra canci\u00f3n es pr\u00e1cticamente una oraci\u00f3n a la que todo el pueblo de Hornachos se une&#8230; &#8220;siempre te voy a esperar&#8221;, solidariz\u00e1ndonos con la impotencia que siente esta familia destrozada que ve pasar con angustia los d\u00edas sin recibir noticia alguna;\u00bfde d\u00f3nde se sacan fuerzas para seguir luchando, para seguir buscando, para seguir aguantando?<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/sBH0BLCHFTs\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Esperar, como una prueba de amor, firmes en la convicci\u00f3n de que vas a volver, de que vamos a encontrarte&#8230; en esta espera, en esta b\u00fasqueda, cada uno arrima el hombro como puede, nosotros desde la m\u00fasica, el respeto y la esperanza.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El pueblo de Hornachos aguanta la respiraci\u00f3n desde que el pasado 9 de Mayo nuestra vecina Francisca Cadenas desapareciera de forma inexplicable, dejando a su familia y a todos los que la conoc\u00edamos sin saber qu\u00e9 hacer, m\u00e1s all\u00e1 de seguir busc\u00e1ndola por las cercan\u00edas, compartir su imagen en los medios de comunicaci\u00f3n, enviar carteles [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":137,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[41,42,40,20],"_links":{"self":[{"href":"https:\/\/blogs.hoy.es\/musica-en-el-tiempo\/wp-json\/wp\/v2\/posts\/196"}],"collection":[{"href":"https:\/\/blogs.hoy.es\/musica-en-el-tiempo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.hoy.es\/musica-en-el-tiempo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.hoy.es\/musica-en-el-tiempo\/wp-json\/wp\/v2\/users\/137"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.hoy.es\/musica-en-el-tiempo\/wp-json\/wp\/v2\/comments?post=196"}],"version-history":[{"count":3,"href":"https:\/\/blogs.hoy.es\/musica-en-el-tiempo\/wp-json\/wp\/v2\/posts\/196\/revisions"}],"predecessor-version":[{"id":202,"href":"https:\/\/blogs.hoy.es\/musica-en-el-tiempo\/wp-json\/wp\/v2\/posts\/196\/revisions\/202"}],"wp:attachment":[{"href":"https:\/\/blogs.hoy.es\/musica-en-el-tiempo\/wp-json\/wp\/v2\/media?parent=196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.hoy.es\/musica-en-el-tiempo\/wp-json\/wp\/v2\/categories?post=196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.hoy.es\/musica-en-el-tiempo\/wp-json\/wp\/v2\/tags?post=196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}