{"id":25,"date":"2016-03-05T20:24:01","date_gmt":"2016-03-05T19:24:01","guid":{"rendered":"http:\/\/blogs.hoy.es\/musica-en-el-tiempo\/?p=25"},"modified":"2019-01-11T23:18:25","modified_gmt":"2019-01-11T22:18:25","slug":"ser-uno-mismo","status":"publish","type":"post","link":"https:\/\/blogs.hoy.es\/musica-en-el-tiempo\/2016\/03\/05\/ser-uno-mismo\/","title":{"rendered":"Ser uno mismo"},"content":{"rendered":"<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/4tXoCifRW78\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><br \/>\nLa vida del m\u00fasico argentino<strong> Atahualpa Yupanqui<\/strong> que en quechua significa \u201cel que viene de lejanas tierras para decir algo\u201d, cuyo verdadero nombre era H\u00e9ctor Roberto Chavero, dio un giro radical cuando en 1917 con su familia pas\u00f3 unas vacaciones en<strong> Tucum\u00e1n<\/strong>, y all\u00ed conoci\u00f3 un nuevo paisaje, una nueva m\u00fasica, con los instrumentos propios del pueblo ind\u00edgena. Desde aquel momento su compromiso con este pueblo le llev\u00f3 a transformar su identidad, cambiar su nombre, y a propagar su m\u00fasica por el mundo.<br \/>\nEn esta<strong> milonga<\/strong> Atahualpa music\u00f3 el poema de su amigo <strong>Romildo Risso<\/strong> del que sol\u00eda relatar la siguiente an\u00e9cdota; &#8220;Yo ten\u00eda un amigo a quien recuerdo muy siempre, como decimos en el campo, un amigo que muri\u00f3 hace treinta a\u00f1os o algo parecido, el autor de Los ejes de mi carreta, que me dec\u00eda: hay dos clases de viejo; aquel que pas\u00f3 la vida acumulando experiencia y aquel otro que se pas\u00f3 la vida amontonando tonter\u00edas y se cree que es experiencia.&#8221;<br \/>\n<strong>Los ejes de mi carreta<\/strong> ha aparecido siempre como un himno al <strong>inconformismo<\/strong>, a la afirmaci\u00f3n de uno mismo aunque eso pueda causar extra\u00f1eza en los dem\u00e1s, a ser como uno quiere o puede ser a pesar de lo que te digan, desde la extrema y tozuda sencillez de no dejar que el mundo te cambie aunque parezca que lo que est\u00e1s haciendo no tiene mucho sentido. \u00bfCu\u00e1ntas veces escuchamos gente que nos aconsejan con la mejor intenci\u00f3n? \u00bfCu\u00e1ntas veces uno se da cuenta que su vida chirr\u00eda, que podr\u00eda hacer las cosas de otro modo, seguramente mejor, que podr\u00eda engrasar los ejes y ya no sonar\u00edan?<br \/>\n<a href=\"\/musica-en-el-tiempo\/wp-content\/uploads\/sites\/114\/2016\/03\/6973496875_c43e7427b6_b1.jpg\"><img loading=\"lazy\" src=\"\/musica-en-el-tiempo\/wp-content\/uploads\/sites\/114\/2016\/03\/6973496875_c43e7427b6_b1.jpg\" alt=\"\" title=\"\" width=\"1024\" height=\"615\" class=\"alignnone size-full wp-image-28\" srcset=\"https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/114\/2016\/03\/6973496875_c43e7427b6_b1.jpg 1024w, https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/114\/2016\/03\/6973496875_c43e7427b6_b1-300x180.jpg 300w, https:\/\/static-blogs.hoy.es\/wp-content\/uploads\/sites\/114\/2016\/03\/6973496875_c43e7427b6_b1-768x461.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><br \/>\nY no siempre conseguimos explicar (a veces ni a nosotros mismos) que no somos unos abandonados, la realidad es que somos como somos, que dejamos que los ejes chirr\u00eden cuando podr\u00edamos engrasarlos porque as\u00ed es como nos gusta; pero tambi\u00e9n podr\u00edamos peinarnos de otra manera, buscar otro trabajo mejor que este que buscamos pero que no tiene futuro, dejar a esa chica que tanto te gusta pero que no te conviene, ponerte derecho que parece que siempre vas cansado, quitarte esa barba, (con <strong>lo guapo que estas afeitado<\/strong>&#8230; que dir\u00eda tu madre).Pues s\u00ed, seguramente todo eso es verdad; pero como dec\u00eda el gran Atahualpa:<br \/>\n&#8220;Si a m\u00ed me gusta que suenen \u00bf<strong>pa qu\u00e9 los quiero engrasaos<\/strong>?&#8221;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La vida del m\u00fasico argentino Atahualpa Yupanqui que en quechua significa \u201cel que viene de lejanas tierras para decir algo\u201d, cuyo verdadero nombre era H\u00e9ctor Roberto Chavero, dio un giro radical cuando en 1917 con su familia pas\u00f3 unas vacaciones en Tucum\u00e1n, y all\u00ed conoci\u00f3 un nuevo paisaje, una nueva m\u00fasica, con los instrumentos propios [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":137,"featured_media":29,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[3,5,12,27,31],"_links":{"self":[{"href":"https:\/\/blogs.hoy.es\/musica-en-el-tiempo\/wp-json\/wp\/v2\/posts\/25"}],"collection":[{"href":"https:\/\/blogs.hoy.es\/musica-en-el-tiempo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.hoy.es\/musica-en-el-tiempo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.hoy.es\/musica-en-el-tiempo\/wp-json\/wp\/v2\/users\/137"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.hoy.es\/musica-en-el-tiempo\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":2,"href":"https:\/\/blogs.hoy.es\/musica-en-el-tiempo\/wp-json\/wp\/v2\/posts\/25\/revisions"}],"predecessor-version":[{"id":359,"href":"https:\/\/blogs.hoy.es\/musica-en-el-tiempo\/wp-json\/wp\/v2\/posts\/25\/revisions\/359"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.hoy.es\/musica-en-el-tiempo\/wp-json\/wp\/v2\/media\/29"}],"wp:attachment":[{"href":"https:\/\/blogs.hoy.es\/musica-en-el-tiempo\/wp-json\/wp\/v2\/media?parent=25"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.hoy.es\/musica-en-el-tiempo\/wp-json\/wp\/v2\/categories?post=25"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.hoy.es\/musica-en-el-tiempo\/wp-json\/wp\/v2\/tags?post=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}